{"id":1896,"date":"2020-07-24T17:18:00","date_gmt":"2020-07-24T15:18:00","guid":{"rendered":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/?p=1896"},"modified":"2020-08-02T17:18:22","modified_gmt":"2020-08-02T15:18:22","slug":"lenovo-partner-hub-portal-partners","status":"publish","type":"post","link":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/lenovo-partner-hub-portal-partners\/","title":{"rendered":"Lenovo Partner Hub, portal con herramientas de venta personalizada para partners"},"content":{"rendered":"<p>Lenovo ha anunciado la apertura de un nuevo portal para sus <a href=\"http:\/\/muycomputerpro.com\/universo-lenovo\/?s=partners\" target=\"_blank\" rel=\"noopener\">partners<\/a>, con herramientas de venta personalizada y en tiempo real. Se trata del <strong>Lenovo Partner Hub<\/strong>, que estar\u00e1 disponible a partir del pr\u00f3ximo 27 de julio en varios mercados.<\/p>\n<p>Con este portal, la compa\u00f1\u00eda tiene como objetivo <strong>estrechar la colaboraci\u00f3n entre los partners<\/strong> del canal de distribuci\u00f3n y los comerciales de sus distintas unidades de negocio. Se ha dise\u00f1ado sobre todo para los partners de PC y dispositivos inteligentes del Grupo de Dispositivos Inteligentes de Lenovo, as\u00ed como para los del Grupo de Centros de Datos.<\/p>\n<p>Ofrece un <strong>acceso \u00fanico a herramientas y recursos<\/strong>, as\u00ed como a la informaci\u00f3n inteligente y personalizada que es m\u00e1s importante para las distintas necesidades, mercado e historial de cada socio. Lenovo Partner Hub cuenta con un sistema de precios inteligentes, es decir, con un motor de precios racionalizado, que adem\u00e1s integra un registro de operaciones. Tambi\u00e9n cuenta con bonos de adquisici\u00f3n y para nuevos clientes.<\/p>\n<p>Aparte de esto, el portal ofrece un sistema de venta conjunta digital, que incluye activos de m\u00e1rketing digital, servicios para socios, programas especializados y recompensas. Para <strong>Jammi Tu<\/strong>, uno de los<strong> Vicepresidentes de Lenovo<\/strong>, \u00ab<em>Lenovo Partner Hub ofrece a nuestros partners una experiencia mejorada, m\u00e1s productividad y mayor velocidad de ventas, y est\u00e1 dise\u00f1ado para una dr\u00e1stica aceleraci\u00f3n de sus negocios. El nuevo portal es testimonio de compromiso a largo plazo de Lenovo con el \u00e9xito de nuestros partners, y un hito en nuestra senda de transformaci\u00f3n digital<\/em>\u00ab.<\/p>\n<p>Este hub incluye un portal personalizado en el que los partners pueden acceder a los materiales y la informaci\u00f3n relevantes para su negocio, en funci\u00f3n de los roles especializados que accedan a \u00e9l. Entre esta informaci\u00f3n hay un <strong>panel de control con los resultados de ventas<\/strong>, tambi\u00e9n personalizado. Con \u00e9l se pueden controlar de un solo vistazo los resultados de ventas y el seguimiento de los KPIs. De esta forma se consigue que los partners mejoren la visibilidad y la eficiencia.<\/p>\n<p>El portal tambi\u00e9n ofrece diversos res\u00famenes de ventas personalizados, que tienen como objetivo el cierre de operaciones de manera m\u00e1s r\u00e1pida y eficiente. Otra de sus funciones, <strong>Lenovo Bid Platform<\/strong>, funciona como motor de precios para los partners de los grupos de Dispositivos inteligentes y Centros de datos de la compa\u00f1\u00eda. En general, el portal da acceso sencillo a los clientes del grupo, que cuentan con acceso a cat\u00e1logos de productos, registro de operaciones, protecci\u00f3n de operacione y bonos y c\u00f3digos de descuento para nuevos clientes.<\/p>\n<p><strong>Wilfredo Sotolongo<\/strong>, <strong>Director de clientes del Grupo de centros de datos de Lenovo<\/strong>, se\u00f1ala que \u00ab<em>Lenovo Partner Hub es otro ejemplo de nuestra estrategia de priorizaci\u00f3n del canal de distribuci\u00f3n, y est\u00e1 dise\u00f1ado para ayudar a nuestros partners a brindar una mejor experiencia de sus clientes, proporcion\u00e1ndoles la informaci\u00f3n, las herramientas y los precios para poner a su disposici\u00f3n soluciones superiores en menos tiempo y creando m\u00e1s valor<\/em>\u00ab.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lenovo ha anunciado la apertura de un nuevo portal para sus partners, con herramientas de venta personalizada y en tiempo real. Se trata del Lenovo Partner Hub, que estar\u00e1 disponible[&#8230;]<\/p>\n","protected":false},"author":10,"featured_media":1898,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[107,452,453],"class_list":["post-1896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-lenovo","tag-lenovo-partner-hub","tag-partners"],"_links":{"self":[{"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/posts\/1896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/comments?post=1896"}],"version-history":[{"count":2,"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/posts\/1896\/revisions"}],"predecessor-version":[{"id":1899,"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/posts\/1896\/revisions\/1899"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/media\/1898"}],"wp:attachment":[{"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/media?parent=1896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/categories?post=1896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muycomputerpro.com\/universo-lenovo\/wp-json\/wp\/v2\/tags?post=1896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}